{"id":14545,"date":"2022-07-18T11:29:46","date_gmt":"2022-07-18T16:29:46","guid":{"rendered":"https:\/\/mbs.edu.co\/?p=14545"},"modified":"2023-06-02T10:39:59","modified_gmt":"2023-06-02T15:39:59","slug":"no-podemos-hablar-de-una-educacion-de-calidad-si-esta-no-transforma-la-calidad-de-vida","status":"publish","type":"post","link":"https:\/\/mbs.edu.co\/fr\/no-podemos-hablar-de-una-educacion-de-calidad-si-esta-no-transforma-la-calidad-de-vida\/","title":{"rendered":"No podemos hablar de una educaci\u00f3n de  calidad si esta no transforma  la calidad de vida&#8230;"},"content":{"rendered":"<div data-elementor-type=\"wp-post\" data-elementor-id=\"14545\" class=\"elementor elementor-14545\" data-elementor-post-type=\"post\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-127520b6 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"127520b6\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-62920a53\" data-id=\"62920a53\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-3d167e21 elementor-widget elementor-widget-text-editor\" data-id=\"3d167e21\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\t<p><\/p>\n<div class=\"wp-block-image\">\n<figure class=\"aligncenter size-large\"><img fetchpriority=\"high\" decoding=\"async\" class=\"alignnone wp-image-14743 size-full\" src=\"https:\/\/mbs.edu.co\/wp-content\/uploads\/2022\/07\/estudiante.jpg\" alt=\"\" width=\"1024\" height=\"262\" srcset=\"https:\/\/mbs.edu.co\/wp-content\/uploads\/2022\/07\/estudiante.jpg 1024w, https:\/\/mbs.edu.co\/wp-content\/uploads\/2022\/07\/estudiante-300x77.jpg 300w, https:\/\/mbs.edu.co\/wp-content\/uploads\/2022\/07\/estudiante-768x197.jpg 768w, https:\/\/mbs.edu.co\/wp-content\/uploads\/2022\/07\/estudiante-18x5.jpg 18w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/>\n<p>\u00a0<\/p>\n<p>\u00a0<\/p>\n<figcaption><em>MBS \u00b7<\/em> Todos los espacios del Montessori British School son obras de arte, que contagian a los estudiantes con su creatividad.<\/figcaption>\n<\/figure>\n<\/div>\n<p><\/p>\n<p><\/p>\n<p class=\"has-drop-cap\">Claudia D\u00edaz, directora del Montessori British School, propicia una transformaci\u00f3n en el estilo de vida (lifestyle) de los estudiantes y de sus familias. \u00bfQu\u00e9 significa esto?, y \u00bfc\u00f3mo lo hace? Ella defiende una educaci\u00f3n que trascienda, a la que llama educaci\u00f3n de vida: una que no disuena con el rendimiento escolar, como comprueban los excelentes resultados que obtienen sus estudiantes, casi siempre los primeros lugares, en las pruebas Saber 11, los Cambridge International Examinations, el Delf (pruebas de proficiencia del franc\u00e9s) y YCT (pruebas de mandar\u00edn).<\/p>\n<p>Esta educaci\u00f3n de vida tiene 3 pilares importantes:<\/p>\n<p><em>1. Una transformaci\u00f3n de la relaci\u00f3n con nuestro cuerpo<\/em><br \/>En el Montessori British School, todas las clases, especialmente las de ciencias, tienen como eje fundamental cambiar esta relaci\u00f3n. En este colegio, a los ni\u00f1os se les ense\u00f1a, con una variedad de experimentos y un aprendizaje experiencial, a alimentarse bien seg\u00fan una nueva ciencia llamada epigen\u00e9tica, que se fundamenta en que tenemos genes predispuestos a diferentes enfermedades, pero con \u201cinterruptores\u201d de on y off que prendemos o apagamos dependiendo de nuestro lifestyle. Los padres tambi\u00e9n toman clases de cocina hol\u00edstica para ayudar a transformar la alimentaci\u00f3n en casa.<\/p>\n<p>2. <em>Una transformaci\u00f3n en la relaci\u00f3n que tenemos con nosotros mismos.<\/em> <br \/>En el Montessori British School, los estudiantes aprenden que ellos son conductores de su propio destino; que, sin importar las circunstancias, ellos pueden elegir la felicidad. Este programa implica una educaci\u00f3n simult\u00e1nea en que los estudiantes toman una clase llamada Inteligencia Emocional, y los padres, sincronizados, trabajan online en el blog www.minddriver.com.<\/p>\n<p>3. <em>Una transformaci\u00f3n en la relaci\u00f3n que tenemos con los dem\u00e1s.<\/em> <br \/>Ubuntu est\u00e1 firmemente arraigado en el colegio, y quiere decir: \u201cYo soy porque nosotros somos\u201d. Aqu\u00ed los estudiantes se entienden como seres sociales, cuyas relaciones con el otro los catapultan hacia el \u00e9xito y la felicidad. En el Montessori British School, los estudiantes dominan 4 idiomas \u2014ingl\u00e9s, franc\u00e9s, mandar\u00edn y espa\u00f1ol\u2014, pero su aprendizaje no acaba ah\u00ed, sino que aprenden tambi\u00e9n a entender estas culturas. As\u00ed, se convierten en verdaderos seres globalizados.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-f0d4e97 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"f0d4e97\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-e89b654\" data-id=\"e89b654\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-1c26402 elementor-cta--skin-classic elementor-animated-content elementor-bg-transform elementor-bg-transform-zoom-in elementor-widget elementor-widget-call-to-action\" data-id=\"1c26402\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"call-to-action.default\">\n\t\t\t\t\t\t\t<div class=\"elementor-cta\">\n\t\t\t\t\t<div class=\"elementor-cta__bg-wrapper\">\n\t\t\t\t<div class=\"elementor-cta__bg elementor-bg\" style=\"background-image: url(https:\/\/mbs.edu.co\/wp-content\/uploads\/2022\/06\/ADMISIONES-PIERROT_075.png);\" role=\"img\" aria-label=\"ADMISIONES-PIERROT_075\"><\/div>\n\t\t\t\t<div class=\"elementor-cta__bg-overlay\"><\/div>\n\t\t\t<\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-cta__content\">\n\t\t\t\t\n\t\t\t\t\t\t\t\t\t<h2 class=\"elementor-cta__title elementor-cta__content-item elementor-content-item\">\n\t\t\t\t\t\tRegresar\t\t\t\t\t<\/h2>\n\t\t\t\t\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-cta__description elementor-cta__content-item elementor-content-item\">\n\t\t\t\t\t\tPrensa, somos un referente a seguir <span style=\"font-family: ABeeZee, var(--nv-fallback-ff)\"><\/span><br>\t\t\t\t\t<\/div>\n\t\t\t\t\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-cta__button-wrapper elementor-cta__content-item elementor-content-item\">\n\t\t\t\t\t<a class=\"elementor-cta__button elementor-button elementor-size-\" href=\"https:\/\/mbs.edu.co\/fr\/montessori-british-school\/\">\n\t\t\t\t\t\tVolver atr\u00e1s\t\t\t\t\t<\/a>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-12737c1\" data-id=\"12737c1\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>","protected":false},"excerpt":{"rendered":"<p>Claudia D\u00edaz, directora del Montessori British School, propicia una transformaci\u00f3n en el estilo de vida (lifestyle) de los estudiantes y de sus familias. \u00bfQu\u00e9 significa esto?, y \u00bfc\u00f3mo lo hace? Ella defiende una educaci\u00f3n que trascienda, a la que llama educaci\u00f3n de vida: una que no disuena con el rendimiento escolar, como comprueban los excelentes&hellip;&nbsp;<a href=\"https:\/\/mbs.edu.co\/fr\/no-podemos-hablar-de-una-educacion-de-calidad-si-esta-no-transforma-la-calidad-de-vida\/\" rel=\"bookmark\">Lire la suite &raquo;<span class=\"screen-reader-text\">No podemos hablar de una educaci\u00f3n de  calidad si esta no transforma  la calidad de vida&#8230;<\/span><\/a><\/p>","protected":false},"author":6,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"neve_meta_sidebar":"","neve_meta_container":"","neve_meta_enable_content_width":"","neve_meta_content_width":0,"neve_meta_title_alignment":"","neve_meta_author_avatar":"","neve_post_elements_order":"","neve_meta_disable_header":"","neve_meta_disable_footer":"","neve_meta_disable_title":"","footnotes":""},"categories":[2],"tags":[],"class_list":["post-14545","post","type-post","status-publish","format-standard","hentry","category-uncategorized"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>No podemos hablar de una educaci\u00f3n de calidad si esta no transforma la calidad de vida... &#8226; Montessori British School<\/title>\n<meta name=\"description\" content=\"Montessori British School, propicia una transformaci\u00f3n en el estilo de vida (lifestyle) de los estudiantes y de sus familias.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/mbs.edu.co\/fr\/no-podemos-hablar-de-una-educacion-de-calidad-si-esta-no-transforma-la-calidad-de-vida\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"No podemos hablar de una educaci\u00f3n de calidad si esta no transforma la calidad de vida... &#8226; Montessori British School\" \/>\n<meta property=\"og:description\" content=\"Montessori British School, propicia una transformaci\u00f3n en el estilo de vida (lifestyle) de los estudiantes y de sus familias.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/mbs.edu.co\/fr\/no-podemos-hablar-de-una-educacion-de-calidad-si-esta-no-transforma-la-calidad-de-vida\/\" \/>\n<meta property=\"og:site_name\" content=\"Montessori British School\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/montessoribritishschool\" \/>\n<meta property=\"article:published_time\" content=\"2022-07-18T16:29:46+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2023-06-02T15:39:59+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/mbs.edu.co\/wp-content\/uploads\/2022\/07\/estudiante.jpg\" \/>\n<meta name=\"author\" content=\"admin\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"admin\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/mbs.edu.co\\\/no-podemos-hablar-de-una-educacion-de-calidad-si-esta-no-transforma-la-calidad-de-vida\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/mbs.edu.co\\\/no-podemos-hablar-de-una-educacion-de-calidad-si-esta-no-transforma-la-calidad-de-vida\\\/\"},\"author\":{\"name\":\"admin\",\"@id\":\"https:\\\/\\\/mbs.edu.co\\\/#\\\/schema\\\/person\\\/17c898cc62fd38e128e406c4cf778a72\"},\"headline\":\"No podemos hablar de una educaci\u00f3n de calidad si esta no transforma la calidad de vida&#8230;\",\"datePublished\":\"2022-07-18T16:29:46+00:00\",\"dateModified\":\"2023-06-02T15:39:59+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/mbs.edu.co\\\/no-podemos-hablar-de-una-educacion-de-calidad-si-esta-no-transforma-la-calidad-de-vida\\\/\"},\"wordCount\":410,\"publisher\":{\"@id\":\"https:\\\/\\\/mbs.edu.co\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/mbs.edu.co\\\/no-podemos-hablar-de-una-educacion-de-calidad-si-esta-no-transforma-la-calidad-de-vida\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/mbs.edu.co\\\/wp-content\\\/uploads\\\/2022\\\/07\\\/estudiante.jpg\",\"articleSection\":[\"Uncategorized\"],\"inLanguage\":\"fr-FR\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/mbs.edu.co\\\/no-podemos-hablar-de-una-educacion-de-calidad-si-esta-no-transforma-la-calidad-de-vida\\\/\",\"url\":\"https:\\\/\\\/mbs.edu.co\\\/no-podemos-hablar-de-una-educacion-de-calidad-si-esta-no-transforma-la-calidad-de-vida\\\/\",\"name\":\"No podemos hablar de una educaci\u00f3n de calidad si esta no transforma la calidad de vida... &#8226; Montessori British School\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/mbs.edu.co\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/mbs.edu.co\\\/no-podemos-hablar-de-una-educacion-de-calidad-si-esta-no-transforma-la-calidad-de-vida\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/mbs.edu.co\\\/no-podemos-hablar-de-una-educacion-de-calidad-si-esta-no-transforma-la-calidad-de-vida\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/mbs.edu.co\\\/wp-content\\\/uploads\\\/2022\\\/07\\\/estudiante.jpg\",\"datePublished\":\"2022-07-18T16:29:46+00:00\",\"dateModified\":\"2023-06-02T15:39:59+00:00\",\"description\":\"Montessori British School, propicia una transformaci\u00f3n en el estilo de vida (lifestyle) de los estudiantes y de sus familias.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/mbs.edu.co\\\/no-podemos-hablar-de-una-educacion-de-calidad-si-esta-no-transforma-la-calidad-de-vida\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/mbs.edu.co\\\/no-podemos-hablar-de-una-educacion-de-calidad-si-esta-no-transforma-la-calidad-de-vida\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/mbs.edu.co\\\/no-podemos-hablar-de-una-educacion-de-calidad-si-esta-no-transforma-la-calidad-de-vida\\\/#primaryimage\",\"url\":\"https:\\\/\\\/mbs.edu.co\\\/wp-content\\\/uploads\\\/2022\\\/07\\\/estudiante.jpg\",\"contentUrl\":\"https:\\\/\\\/mbs.edu.co\\\/wp-content\\\/uploads\\\/2022\\\/07\\\/estudiante.jpg\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/mbs.edu.co\\\/no-podemos-hablar-de-una-educacion-de-calidad-si-esta-no-transforma-la-calidad-de-vida\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/mbs.edu.co\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"No podemos hablar de una educaci\u00f3n de calidad si esta no transforma la calidad de vida&#8230;\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/mbs.edu.co\\\/#website\",\"url\":\"https:\\\/\\\/mbs.edu.co\\\/\",\"name\":\"Montessori British School\",\"description\":\"Colegio mixto calendario B, internacional, multiling\u00fce e intercultural que basa su ense\u00f1anza en la creatividad y la expresi\u00f3n.\",\"publisher\":{\"@id\":\"https:\\\/\\\/mbs.edu.co\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/mbs.edu.co\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/mbs.edu.co\\\/#organization\",\"name\":\"Montessori British School\",\"url\":\"https:\\\/\\\/mbs.edu.co\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/mbs.edu.co\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/mbs.edu.co\\\/wp-content\\\/uploads\\\/2020\\\/10\\\/LOGO-MBS-montessori-2.png\",\"contentUrl\":\"https:\\\/\\\/mbs.edu.co\\\/wp-content\\\/uploads\\\/2020\\\/10\\\/LOGO-MBS-montessori-2.png\",\"width\":800,\"height\":366,\"caption\":\"Montessori British School\"},\"image\":{\"@id\":\"https:\\\/\\\/mbs.edu.co\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/montessoribritishschool\",\"https:\\\/\\\/www.instagram.com\\\/oficialmbs\\\/\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/montessori-british-school-mbs\\\/mycompany\\\/?viewAsMember=true\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/mbs.edu.co\\\/#\\\/schema\\\/person\\\/17c898cc62fd38e128e406c4cf778a72\",\"name\":\"admin\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/59256d3338691b9e98f2122a13934b30a3a6fcb6818583d0374ddf2fb85ea2c2?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/59256d3338691b9e98f2122a13934b30a3a6fcb6818583d0374ddf2fb85ea2c2?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/59256d3338691b9e98f2122a13934b30a3a6fcb6818583d0374ddf2fb85ea2c2?s=96&d=mm&r=g\",\"caption\":\"admin\"},\"sameAs\":[\"https:\\\/\\\/mbs.edu.co\\\/\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"No podemos hablar de una educaci\u00f3n de calidad si esta no transforma la calidad de vida... &#8226; Montessori British School","description":"Montessori British School, propicia una transformaci\u00f3n en el estilo de vida (lifestyle) de los estudiantes y de sus familias.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/mbs.edu.co\/fr\/no-podemos-hablar-de-una-educacion-de-calidad-si-esta-no-transforma-la-calidad-de-vida\/","og_locale":"fr_FR","og_type":"article","og_title":"No podemos hablar de una educaci\u00f3n de calidad si esta no transforma la calidad de vida... &#8226; Montessori British School","og_description":"Montessori British School, propicia una transformaci\u00f3n en el estilo de vida (lifestyle) de los estudiantes y de sus familias.","og_url":"https:\/\/mbs.edu.co\/fr\/no-podemos-hablar-de-una-educacion-de-calidad-si-esta-no-transforma-la-calidad-de-vida\/","og_site_name":"Montessori British School","article_publisher":"https:\/\/www.facebook.com\/montessoribritishschool","article_published_time":"2022-07-18T16:29:46+00:00","article_modified_time":"2023-06-02T15:39:59+00:00","og_image":[{"url":"https:\/\/mbs.edu.co\/wp-content\/uploads\/2022\/07\/estudiante.jpg","type":"","width":"","height":""}],"author":"admin","twitter_card":"summary_large_image","twitter_misc":{"\u00c9crit par":"admin","Dur\u00e9e de lecture estim\u00e9e":"2 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/mbs.edu.co\/no-podemos-hablar-de-una-educacion-de-calidad-si-esta-no-transforma-la-calidad-de-vida\/#article","isPartOf":{"@id":"https:\/\/mbs.edu.co\/no-podemos-hablar-de-una-educacion-de-calidad-si-esta-no-transforma-la-calidad-de-vida\/"},"author":{"name":"admin","@id":"https:\/\/mbs.edu.co\/#\/schema\/person\/17c898cc62fd38e128e406c4cf778a72"},"headline":"No podemos hablar de una educaci\u00f3n de calidad si esta no transforma la calidad de vida&#8230;","datePublished":"2022-07-18T16:29:46+00:00","dateModified":"2023-06-02T15:39:59+00:00","mainEntityOfPage":{"@id":"https:\/\/mbs.edu.co\/no-podemos-hablar-de-una-educacion-de-calidad-si-esta-no-transforma-la-calidad-de-vida\/"},"wordCount":410,"publisher":{"@id":"https:\/\/mbs.edu.co\/#organization"},"image":{"@id":"https:\/\/mbs.edu.co\/no-podemos-hablar-de-una-educacion-de-calidad-si-esta-no-transforma-la-calidad-de-vida\/#primaryimage"},"thumbnailUrl":"https:\/\/mbs.edu.co\/wp-content\/uploads\/2022\/07\/estudiante.jpg","articleSection":["Uncategorized"],"inLanguage":"fr-FR"},{"@type":"WebPage","@id":"https:\/\/mbs.edu.co\/no-podemos-hablar-de-una-educacion-de-calidad-si-esta-no-transforma-la-calidad-de-vida\/","url":"https:\/\/mbs.edu.co\/no-podemos-hablar-de-una-educacion-de-calidad-si-esta-no-transforma-la-calidad-de-vida\/","name":"No podemos hablar de una educaci\u00f3n de calidad si esta no transforma la calidad de vida... &#8226; Montessori British School","isPartOf":{"@id":"https:\/\/mbs.edu.co\/#website"},"primaryImageOfPage":{"@id":"https:\/\/mbs.edu.co\/no-podemos-hablar-de-una-educacion-de-calidad-si-esta-no-transforma-la-calidad-de-vida\/#primaryimage"},"image":{"@id":"https:\/\/mbs.edu.co\/no-podemos-hablar-de-una-educacion-de-calidad-si-esta-no-transforma-la-calidad-de-vida\/#primaryimage"},"thumbnailUrl":"https:\/\/mbs.edu.co\/wp-content\/uploads\/2022\/07\/estudiante.jpg","datePublished":"2022-07-18T16:29:46+00:00","dateModified":"2023-06-02T15:39:59+00:00","description":"Montessori British School, propicia una transformaci\u00f3n en el estilo de vida (lifestyle) de los estudiantes y de sus familias.","breadcrumb":{"@id":"https:\/\/mbs.edu.co\/no-podemos-hablar-de-una-educacion-de-calidad-si-esta-no-transforma-la-calidad-de-vida\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/mbs.edu.co\/no-podemos-hablar-de-una-educacion-de-calidad-si-esta-no-transforma-la-calidad-de-vida\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/mbs.edu.co\/no-podemos-hablar-de-una-educacion-de-calidad-si-esta-no-transforma-la-calidad-de-vida\/#primaryimage","url":"https:\/\/mbs.edu.co\/wp-content\/uploads\/2022\/07\/estudiante.jpg","contentUrl":"https:\/\/mbs.edu.co\/wp-content\/uploads\/2022\/07\/estudiante.jpg"},{"@type":"BreadcrumbList","@id":"https:\/\/mbs.edu.co\/no-podemos-hablar-de-una-educacion-de-calidad-si-esta-no-transforma-la-calidad-de-vida\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/mbs.edu.co\/"},{"@type":"ListItem","position":2,"name":"No podemos hablar de una educaci\u00f3n de calidad si esta no transforma la calidad de vida&#8230;"}]},{"@type":"WebSite","@id":"https:\/\/mbs.edu.co\/#website","url":"https:\/\/mbs.edu.co\/","name":"Montessori British School","description":"Colegio mixto calendario B, internacional, multiling\u00fce e intercultural que basa su ense\u00f1anza en la creatividad y la expresi\u00f3n.","publisher":{"@id":"https:\/\/mbs.edu.co\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/mbs.edu.co\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/mbs.edu.co\/#organization","name":"Montessori British School","url":"https:\/\/mbs.edu.co\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/mbs.edu.co\/#\/schema\/logo\/image\/","url":"https:\/\/mbs.edu.co\/wp-content\/uploads\/2020\/10\/LOGO-MBS-montessori-2.png","contentUrl":"https:\/\/mbs.edu.co\/wp-content\/uploads\/2020\/10\/LOGO-MBS-montessori-2.png","width":800,"height":366,"caption":"Montessori British School"},"image":{"@id":"https:\/\/mbs.edu.co\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/montessoribritishschool","https:\/\/www.instagram.com\/oficialmbs\/","https:\/\/www.linkedin.com\/company\/montessori-british-school-mbs\/mycompany\/?viewAsMember=true"]},{"@type":"Person","@id":"https:\/\/mbs.edu.co\/#\/schema\/person\/17c898cc62fd38e128e406c4cf778a72","name":"admin","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/secure.gravatar.com\/avatar\/59256d3338691b9e98f2122a13934b30a3a6fcb6818583d0374ddf2fb85ea2c2?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/59256d3338691b9e98f2122a13934b30a3a6fcb6818583d0374ddf2fb85ea2c2?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/59256d3338691b9e98f2122a13934b30a3a6fcb6818583d0374ddf2fb85ea2c2?s=96&d=mm&r=g","caption":"admin"},"sameAs":["https:\/\/mbs.edu.co\/"]}]}},"_links":{"self":[{"href":"https:\/\/mbs.edu.co\/fr\/wp-json\/wp\/v2\/posts\/14545","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/mbs.edu.co\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/mbs.edu.co\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/mbs.edu.co\/fr\/wp-json\/wp\/v2\/users\/6"}],"replies":[{"embeddable":true,"href":"https:\/\/mbs.edu.co\/fr\/wp-json\/wp\/v2\/comments?post=14545"}],"version-history":[{"count":0,"href":"https:\/\/mbs.edu.co\/fr\/wp-json\/wp\/v2\/posts\/14545\/revisions"}],"wp:attachment":[{"href":"https:\/\/mbs.edu.co\/fr\/wp-json\/wp\/v2\/media?parent=14545"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/mbs.edu.co\/fr\/wp-json\/wp\/v2\/categories?post=14545"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/mbs.edu.co\/fr\/wp-json\/wp\/v2\/tags?post=14545"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}