{"id":14462,"date":"2022-07-16T12:08:24","date_gmt":"2022-07-16T17:08:24","guid":{"rendered":"https:\/\/mbs.edu.co\/?p=14462"},"modified":"2023-06-02T11:10:34","modified_gmt":"2023-06-02T16:10:34","slug":"su-hijo-puede-aprender-a-ser-feliz","status":"publish","type":"post","link":"https:\/\/mbs.edu.co\/fr\/su-hijo-puede-aprender-a-ser-feliz\/","title":{"rendered":"\u00bfSu hijo puede aprender a ser feliz?"},"content":{"rendered":"<div data-elementor-type=\"wp-post\" data-elementor-id=\"14462\" class=\"elementor elementor-14462\" data-elementor-post-type=\"post\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-127520b6 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"127520b6\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-62920a53\" data-id=\"62920a53\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-3d167e21 elementor-widget elementor-widget-text-editor\" data-id=\"3d167e21\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\t<p><\/p>\n<div class=\"wp-block-image\">\n<figure class=\"aligncenter size-large\"><img fetchpriority=\"high\" decoding=\"async\" class=\"alignnone wp-image-14715 size-full\" src=\"https:\/\/mbs.edu.co\/wp-content\/uploads\/2022\/07\/17.jpg\" alt=\"\" width=\"1024\" height=\"262\" srcset=\"https:\/\/mbs.edu.co\/wp-content\/uploads\/2022\/07\/17.jpg 1024w, https:\/\/mbs.edu.co\/wp-content\/uploads\/2022\/07\/17-300x77.jpg 300w, https:\/\/mbs.edu.co\/wp-content\/uploads\/2022\/07\/17-768x197.jpg 768w, https:\/\/mbs.edu.co\/wp-content\/uploads\/2022\/07\/17-18x5.jpg 18w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/>\n<p>\u00a0<\/p>\n<p>\u00a0<\/p>\n<p>\u00a0<\/p>\n<figcaption><em>MBS \u00b7<\/em> Todos los espacios del Montessori British School son obras de arte, que contagian a los estudiantes con su creatividad.<\/figcaption>\n<\/figure>\n<\/div>\n<p><\/p>\n<p><\/p>\n<p>Todos los padres buscan, construyen y defienden la felicidad de sus hijos, pero a menudo la clave est\u00e1 en las peque\u00f1as cosas y en la buena actitud que tengamos hacia los retos y los obst\u00e1culos que se presentan.<\/p>\n<p>\u00abEs por eso que Claudia D\u00edaz, rectora del prestigioso colegio Montessori British School, en Bogot\u00e1, nos explica, desde su experiencia como educadora y l\u00edder, la posibilidad de aprender a ser feliz: algo que refleja d\u00eda a d\u00eda el colegio que dirige. Con el apoyo de padres y docentes, se han identificado y puesto en pr\u00e1ctica cinco claves para la felicidad.\u00bb<\/p>\n<p><em><strong>1. \u00abNo controlas lo que pasa; controla lo que sientes\u00bb<\/strong><\/em><br \/>\u00abClaudia afirma que este es el primer pilar para ser feliz. Tanto ni\u00f1os como adultos experimentan a diario la sensaci\u00f3n de impotencia frente a lo que ocurre a su alrededor, pero lo importante es que el ni\u00f1o aprenda a darle un significado a lo que sucede y, en funci\u00f3n de eso, experimente una emoci\u00f3n. Claudia afirma que es importante ense\u00f1arles a los ni\u00f1os a asignar a cada situaci\u00f3n la importancia que se merece.<\/p>\n<p>Por supuesto, este no es un aprendizaje que se logra r\u00e1pidamente. Se trata de un trabajo constante, apoyado en actividades en el colegio y en la casa. En el colegio Montessori British School, se aprovechan los temas de clase para resaltar esa habilidad de afrontar con tranquilidad un conflicto y evitar causar da\u00f1o a uno mismo o a los dem\u00e1s.\u00bb<\/p>\n<p><em><strong>2. Todos nacemos inteligentes la diferencia radica en el entrenamiento<\/strong><\/em> <br \/>\u00abEn el entorno escolar, se escuchan a menudo frases como \u00ab soy muy malo para las matem\u00e1ticas\u00bb o \u00ab yo definitivamente no puedo con la ortograf\u00eda\u00bb. Claudia D\u00edaz conoce de primera mano esta situaci\u00f3n, y siempre est\u00e1 presta a decirles a los estudiantes que la diferencia entre una persona que supera sin dificultad los retos acad\u00e9micos y una que no es el inter\u00e9s por aprender algo nuevo, la amplitud de la pr\u00e1ctica y el esfuerzo invertido en ello.<\/p>\n<p>La importancia de este pilar de la felicidad es el empoderamiento de los estudiantes, que dejan de ser v\u00edctimas de una situaci\u00f3n y empiezan a creer en ellos mismos y en sus habilidades para aprender. En el colegio Montessori British School, los estudiantes reconocen que en cada nuevo aprendizaje o emprendimiento hay un reto, y saber que personajes famosos que pasaron a la historia tambi\u00e9n superaron obst\u00e1culos los motiva a concentrarse en sus metas.\u00bb<\/p>\n<p><em><strong>3. No hay problema solo retos<\/strong><\/em> <br \/>\u00abEn lugar de pensar en una soluci\u00f3n para un problema, los estudiantes del colegio Montessori British School saben que para alcanzar un objetivo o superar una dificultad tienen que pasar por un proceso que los va fortalecer intelectual y psicol\u00f3gicamente. Y como los retos van cambiando con el tiempo y se van haciendo m\u00e1s complejos, es importante que como padres y docentes permitamos que los ni\u00f1os afronten sus peque\u00f1as dificultades y poco a poco se vayan fortaleciendo hasta adquirir las competencias necesarias para el mundo real.\u00bb<br \/><br \/><\/p>\n<p><em><strong>4. La Felicidad no es un destino, es un camino<\/strong><\/em><br \/>Si la felicidad se plantea como destino, la vida diaria se convierte en una serie de escalones en los que la felicidad no est\u00e1 presente y se pospone. En cambio, en el colegio Montessori British School, se ense\u00f1a que la felicidad est\u00e1 en cada escal\u00f3n y paso del camino. Como padres, dice la Dra. D\u00edaz, podemos ayudar a identificar esos momentos de felicidad pregunt\u00e1ndoles a los ni\u00f1os todos los d\u00edas acerca de tres momentos felices que hayan experimentado. En poco tiempo, en sus rutinas diarias, los ni\u00f1os estar\u00e1n viviendo y reconociendo esos momentos de felicidad.<br \/><br \/><em><strong>5. Enfoqu\u00e9monos en la gratitud es el camino m\u00e1s directo hacia la felicidad<\/strong><\/em><br \/>Es imposible salvaguardar a los ni\u00f1os de las situaciones adversas; por eso es importante ofrecerles herramientas que les permitan superar esos momentos de dificultad. Los estudiantes del colegio Montessori British School aprenden a ser agradecidos con sus padres, con la vida y con las oportunidades de educaci\u00f3n y socializaci\u00f3n que tienen en el colegio, y as\u00ed reconocen la importancia de enfocarse en el sentimiento de gratitud y no en la tristeza o la rabia que puedan sentir en ocasiones.<br \/><br \/><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-f0d4e97 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"f0d4e97\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-e89b654\" data-id=\"e89b654\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-1c26402 elementor-cta--skin-classic elementor-animated-content elementor-bg-transform elementor-bg-transform-zoom-in elementor-widget elementor-widget-call-to-action\" data-id=\"1c26402\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"call-to-action.default\">\n\t\t\t\t\t\t\t<div class=\"elementor-cta\">\n\t\t\t\t\t<div class=\"elementor-cta__bg-wrapper\">\n\t\t\t\t<div class=\"elementor-cta__bg elementor-bg\" style=\"background-image: url(https:\/\/mbs.edu.co\/wp-content\/uploads\/2022\/06\/ADMISIONES-PIERROT_075.png);\" role=\"img\" aria-label=\"ADMISIONES-PIERROT_075\"><\/div>\n\t\t\t\t<div class=\"elementor-cta__bg-overlay\"><\/div>\n\t\t\t<\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-cta__content\">\n\t\t\t\t\n\t\t\t\t\t\t\t\t\t<h2 class=\"elementor-cta__title elementor-cta__content-item elementor-content-item\">\n\t\t\t\t\t\tRegresar\t\t\t\t\t<\/h2>\n\t\t\t\t\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-cta__description elementor-cta__content-item elementor-content-item\">\n\t\t\t\t\t\tPrensa, somos un referente a seguir <span style=\"font-family: ABeeZee, var(--nv-fallback-ff)\"><\/span><br>\t\t\t\t\t<\/div>\n\t\t\t\t\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-cta__button-wrapper elementor-cta__content-item elementor-content-item\">\n\t\t\t\t\t<a class=\"elementor-cta__button elementor-button elementor-size-\" href=\"https:\/\/mbs.edu.co\/fr\/montessori-british-school\/\">\n\t\t\t\t\t\tVolver atr\u00e1s\t\t\t\t\t<\/a>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-12737c1\" data-id=\"12737c1\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>","protected":false},"excerpt":{"rendered":"<p>Todos los padres buscan, construyen y defienden la felicidad de sus hijos, pero a menudo la clave est\u00e1 en las peque\u00f1as cosas y en la buena actitud que tengamos hacia los retos y los obst\u00e1culos que se presentan. \u00abEs por eso que Claudia D\u00edaz, rectora del prestigioso colegio Montessori British School, en Bogot\u00e1, nos explica,&hellip;&nbsp;<a href=\"https:\/\/mbs.edu.co\/fr\/su-hijo-puede-aprender-a-ser-feliz\/\" rel=\"bookmark\">Lire la suite &raquo;<span class=\"screen-reader-text\">\u00bfSu hijo puede aprender a ser feliz?<\/span><\/a><\/p>","protected":false},"author":6,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"neve_meta_sidebar":"","neve_meta_container":"","neve_meta_enable_content_width":"","neve_meta_content_width":0,"neve_meta_title_alignment":"","neve_meta_author_avatar":"","neve_post_elements_order":"","neve_meta_disable_header":"","neve_meta_disable_footer":"","neve_meta_disable_title":"","footnotes":""},"categories":[2],"tags":[],"class_list":["post-14462","post","type-post","status-publish","format-standard","hentry","category-uncategorized"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>\u00bfSu hijo puede aprender a ser feliz? &#8226; Montessori British School<\/title>\n<meta name=\"description\" content=\"Todos los padres construyen y buscan la felicidad de sus hijos, la clave est\u00e1 en las peque\u00f1as cosas y en la buena actitud hacia los retos.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/mbs.edu.co\/fr\/su-hijo-puede-aprender-a-ser-feliz\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"\u00bfSu hijo puede aprender a ser feliz? &#8226; Montessori British School\" \/>\n<meta property=\"og:description\" content=\"Todos los padres construyen y buscan la felicidad de sus hijos, la clave est\u00e1 en las peque\u00f1as cosas y en la buena actitud hacia los retos.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/mbs.edu.co\/fr\/su-hijo-puede-aprender-a-ser-feliz\/\" \/>\n<meta property=\"og:site_name\" content=\"Montessori British School\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/montessoribritishschool\" \/>\n<meta property=\"article:published_time\" content=\"2022-07-16T17:08:24+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2023-06-02T16:10:34+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/mbs.edu.co\/wp-content\/uploads\/2022\/07\/17.jpg\" \/>\n<meta name=\"author\" content=\"admin\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"admin\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"4 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/mbs.edu.co\\\/su-hijo-puede-aprender-a-ser-feliz\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/mbs.edu.co\\\/su-hijo-puede-aprender-a-ser-feliz\\\/\"},\"author\":{\"name\":\"admin\",\"@id\":\"https:\\\/\\\/mbs.edu.co\\\/#\\\/schema\\\/person\\\/17c898cc62fd38e128e406c4cf778a72\"},\"headline\":\"\u00bfSu hijo puede aprender a ser feliz?\",\"datePublished\":\"2022-07-16T17:08:24+00:00\",\"dateModified\":\"2023-06-02T16:10:34+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/mbs.edu.co\\\/su-hijo-puede-aprender-a-ser-feliz\\\/\"},\"wordCount\":769,\"publisher\":{\"@id\":\"https:\\\/\\\/mbs.edu.co\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/mbs.edu.co\\\/su-hijo-puede-aprender-a-ser-feliz\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/mbs.edu.co\\\/wp-content\\\/uploads\\\/2022\\\/07\\\/17.jpg\",\"articleSection\":[\"Uncategorized\"],\"inLanguage\":\"fr-FR\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/mbs.edu.co\\\/su-hijo-puede-aprender-a-ser-feliz\\\/\",\"url\":\"https:\\\/\\\/mbs.edu.co\\\/su-hijo-puede-aprender-a-ser-feliz\\\/\",\"name\":\"\u00bfSu hijo puede aprender a ser feliz? &#8226; Montessori British School\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/mbs.edu.co\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/mbs.edu.co\\\/su-hijo-puede-aprender-a-ser-feliz\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/mbs.edu.co\\\/su-hijo-puede-aprender-a-ser-feliz\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/mbs.edu.co\\\/wp-content\\\/uploads\\\/2022\\\/07\\\/17.jpg\",\"datePublished\":\"2022-07-16T17:08:24+00:00\",\"dateModified\":\"2023-06-02T16:10:34+00:00\",\"description\":\"Todos los padres construyen y buscan la felicidad de sus hijos, la clave est\u00e1 en las peque\u00f1as cosas y en la buena actitud hacia los retos.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/mbs.edu.co\\\/su-hijo-puede-aprender-a-ser-feliz\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/mbs.edu.co\\\/su-hijo-puede-aprender-a-ser-feliz\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/mbs.edu.co\\\/su-hijo-puede-aprender-a-ser-feliz\\\/#primaryimage\",\"url\":\"https:\\\/\\\/mbs.edu.co\\\/wp-content\\\/uploads\\\/2022\\\/07\\\/17.jpg\",\"contentUrl\":\"https:\\\/\\\/mbs.edu.co\\\/wp-content\\\/uploads\\\/2022\\\/07\\\/17.jpg\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/mbs.edu.co\\\/su-hijo-puede-aprender-a-ser-feliz\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/mbs.edu.co\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"\u00bfSu hijo puede aprender a ser feliz?\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/mbs.edu.co\\\/#website\",\"url\":\"https:\\\/\\\/mbs.edu.co\\\/\",\"name\":\"Montessori British School\",\"description\":\"Colegio mixto calendario B, internacional, multiling\u00fce e intercultural que basa su ense\u00f1anza en la creatividad y la expresi\u00f3n.\",\"publisher\":{\"@id\":\"https:\\\/\\\/mbs.edu.co\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/mbs.edu.co\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/mbs.edu.co\\\/#organization\",\"name\":\"Montessori British School\",\"url\":\"https:\\\/\\\/mbs.edu.co\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/mbs.edu.co\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/mbs.edu.co\\\/wp-content\\\/uploads\\\/2020\\\/10\\\/LOGO-MBS-montessori-2.png\",\"contentUrl\":\"https:\\\/\\\/mbs.edu.co\\\/wp-content\\\/uploads\\\/2020\\\/10\\\/LOGO-MBS-montessori-2.png\",\"width\":800,\"height\":366,\"caption\":\"Montessori British School\"},\"image\":{\"@id\":\"https:\\\/\\\/mbs.edu.co\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/montessoribritishschool\",\"https:\\\/\\\/www.instagram.com\\\/oficialmbs\\\/\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/montessori-british-school-mbs\\\/mycompany\\\/?viewAsMember=true\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/mbs.edu.co\\\/#\\\/schema\\\/person\\\/17c898cc62fd38e128e406c4cf778a72\",\"name\":\"admin\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/59256d3338691b9e98f2122a13934b30a3a6fcb6818583d0374ddf2fb85ea2c2?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/59256d3338691b9e98f2122a13934b30a3a6fcb6818583d0374ddf2fb85ea2c2?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/59256d3338691b9e98f2122a13934b30a3a6fcb6818583d0374ddf2fb85ea2c2?s=96&d=mm&r=g\",\"caption\":\"admin\"},\"sameAs\":[\"https:\\\/\\\/mbs.edu.co\\\/\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"\u00bfSu hijo puede aprender a ser feliz? &#8226; Montessori British School","description":"Todos los padres construyen y buscan la felicidad de sus hijos, la clave est\u00e1 en las peque\u00f1as cosas y en la buena actitud hacia los retos.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/mbs.edu.co\/fr\/su-hijo-puede-aprender-a-ser-feliz\/","og_locale":"fr_FR","og_type":"article","og_title":"\u00bfSu hijo puede aprender a ser feliz? &#8226; Montessori British School","og_description":"Todos los padres construyen y buscan la felicidad de sus hijos, la clave est\u00e1 en las peque\u00f1as cosas y en la buena actitud hacia los retos.","og_url":"https:\/\/mbs.edu.co\/fr\/su-hijo-puede-aprender-a-ser-feliz\/","og_site_name":"Montessori British School","article_publisher":"https:\/\/www.facebook.com\/montessoribritishschool","article_published_time":"2022-07-16T17:08:24+00:00","article_modified_time":"2023-06-02T16:10:34+00:00","og_image":[{"url":"https:\/\/mbs.edu.co\/wp-content\/uploads\/2022\/07\/17.jpg","type":"","width":"","height":""}],"author":"admin","twitter_card":"summary_large_image","twitter_misc":{"\u00c9crit par":"admin","Dur\u00e9e de lecture estim\u00e9e":"4 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/mbs.edu.co\/su-hijo-puede-aprender-a-ser-feliz\/#article","isPartOf":{"@id":"https:\/\/mbs.edu.co\/su-hijo-puede-aprender-a-ser-feliz\/"},"author":{"name":"admin","@id":"https:\/\/mbs.edu.co\/#\/schema\/person\/17c898cc62fd38e128e406c4cf778a72"},"headline":"\u00bfSu hijo puede aprender a ser feliz?","datePublished":"2022-07-16T17:08:24+00:00","dateModified":"2023-06-02T16:10:34+00:00","mainEntityOfPage":{"@id":"https:\/\/mbs.edu.co\/su-hijo-puede-aprender-a-ser-feliz\/"},"wordCount":769,"publisher":{"@id":"https:\/\/mbs.edu.co\/#organization"},"image":{"@id":"https:\/\/mbs.edu.co\/su-hijo-puede-aprender-a-ser-feliz\/#primaryimage"},"thumbnailUrl":"https:\/\/mbs.edu.co\/wp-content\/uploads\/2022\/07\/17.jpg","articleSection":["Uncategorized"],"inLanguage":"fr-FR"},{"@type":"WebPage","@id":"https:\/\/mbs.edu.co\/su-hijo-puede-aprender-a-ser-feliz\/","url":"https:\/\/mbs.edu.co\/su-hijo-puede-aprender-a-ser-feliz\/","name":"\u00bfSu hijo puede aprender a ser feliz? &#8226; Montessori British School","isPartOf":{"@id":"https:\/\/mbs.edu.co\/#website"},"primaryImageOfPage":{"@id":"https:\/\/mbs.edu.co\/su-hijo-puede-aprender-a-ser-feliz\/#primaryimage"},"image":{"@id":"https:\/\/mbs.edu.co\/su-hijo-puede-aprender-a-ser-feliz\/#primaryimage"},"thumbnailUrl":"https:\/\/mbs.edu.co\/wp-content\/uploads\/2022\/07\/17.jpg","datePublished":"2022-07-16T17:08:24+00:00","dateModified":"2023-06-02T16:10:34+00:00","description":"Todos los padres construyen y buscan la felicidad de sus hijos, la clave est\u00e1 en las peque\u00f1as cosas y en la buena actitud hacia los retos.","breadcrumb":{"@id":"https:\/\/mbs.edu.co\/su-hijo-puede-aprender-a-ser-feliz\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/mbs.edu.co\/su-hijo-puede-aprender-a-ser-feliz\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/mbs.edu.co\/su-hijo-puede-aprender-a-ser-feliz\/#primaryimage","url":"https:\/\/mbs.edu.co\/wp-content\/uploads\/2022\/07\/17.jpg","contentUrl":"https:\/\/mbs.edu.co\/wp-content\/uploads\/2022\/07\/17.jpg"},{"@type":"BreadcrumbList","@id":"https:\/\/mbs.edu.co\/su-hijo-puede-aprender-a-ser-feliz\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/mbs.edu.co\/"},{"@type":"ListItem","position":2,"name":"\u00bfSu hijo puede aprender a ser feliz?"}]},{"@type":"WebSite","@id":"https:\/\/mbs.edu.co\/#website","url":"https:\/\/mbs.edu.co\/","name":"Montessori British School","description":"Colegio mixto calendario B, internacional, multiling\u00fce e intercultural que basa su ense\u00f1anza en la creatividad y la expresi\u00f3n.","publisher":{"@id":"https:\/\/mbs.edu.co\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/mbs.edu.co\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/mbs.edu.co\/#organization","name":"Montessori British School","url":"https:\/\/mbs.edu.co\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/mbs.edu.co\/#\/schema\/logo\/image\/","url":"https:\/\/mbs.edu.co\/wp-content\/uploads\/2020\/10\/LOGO-MBS-montessori-2.png","contentUrl":"https:\/\/mbs.edu.co\/wp-content\/uploads\/2020\/10\/LOGO-MBS-montessori-2.png","width":800,"height":366,"caption":"Montessori British School"},"image":{"@id":"https:\/\/mbs.edu.co\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/montessoribritishschool","https:\/\/www.instagram.com\/oficialmbs\/","https:\/\/www.linkedin.com\/company\/montessori-british-school-mbs\/mycompany\/?viewAsMember=true"]},{"@type":"Person","@id":"https:\/\/mbs.edu.co\/#\/schema\/person\/17c898cc62fd38e128e406c4cf778a72","name":"admin","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/secure.gravatar.com\/avatar\/59256d3338691b9e98f2122a13934b30a3a6fcb6818583d0374ddf2fb85ea2c2?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/59256d3338691b9e98f2122a13934b30a3a6fcb6818583d0374ddf2fb85ea2c2?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/59256d3338691b9e98f2122a13934b30a3a6fcb6818583d0374ddf2fb85ea2c2?s=96&d=mm&r=g","caption":"admin"},"sameAs":["https:\/\/mbs.edu.co\/"]}]}},"_links":{"self":[{"href":"https:\/\/mbs.edu.co\/fr\/wp-json\/wp\/v2\/posts\/14462","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/mbs.edu.co\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/mbs.edu.co\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/mbs.edu.co\/fr\/wp-json\/wp\/v2\/users\/6"}],"replies":[{"embeddable":true,"href":"https:\/\/mbs.edu.co\/fr\/wp-json\/wp\/v2\/comments?post=14462"}],"version-history":[{"count":0,"href":"https:\/\/mbs.edu.co\/fr\/wp-json\/wp\/v2\/posts\/14462\/revisions"}],"wp:attachment":[{"href":"https:\/\/mbs.edu.co\/fr\/wp-json\/wp\/v2\/media?parent=14462"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/mbs.edu.co\/fr\/wp-json\/wp\/v2\/categories?post=14462"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/mbs.edu.co\/fr\/wp-json\/wp\/v2\/tags?post=14462"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}