{"id":14450,"date":"2022-07-16T11:25:46","date_gmt":"2022-07-16T16:25:46","guid":{"rendered":"https:\/\/mbs.edu.co\/?p=14450"},"modified":"2023-06-02T11:15:06","modified_gmt":"2023-06-02T16:15:06","slug":"5-oportunidades-que-su-hijo-no-debe-perder","status":"publish","type":"post","link":"https:\/\/mbs.edu.co\/fr\/5-oportunidades-que-su-hijo-no-debe-perder\/","title":{"rendered":"5 Oportunidades que su Hijo no debe perder"},"content":{"rendered":"<div data-elementor-type=\"wp-post\" data-elementor-id=\"14450\" class=\"elementor elementor-14450\" data-elementor-post-type=\"post\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-127520b6 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"127520b6\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-62920a53\" data-id=\"62920a53\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-3d167e21 elementor-widget elementor-widget-text-editor\" data-id=\"3d167e21\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\t<p><\/p>\n<div class=\"wp-block-image\">\n<figure class=\"aligncenter size-large\"><img fetchpriority=\"high\" decoding=\"async\" class=\"alignnone wp-image-14711 size-full\" src=\"https:\/\/mbs.edu.co\/wp-content\/uploads\/2022\/07\/16.jpg\" alt=\"\" width=\"1024\" height=\"262\" srcset=\"https:\/\/mbs.edu.co\/wp-content\/uploads\/2022\/07\/16.jpg 1024w, https:\/\/mbs.edu.co\/wp-content\/uploads\/2022\/07\/16-300x77.jpg 300w, https:\/\/mbs.edu.co\/wp-content\/uploads\/2022\/07\/16-768x197.jpg 768w, https:\/\/mbs.edu.co\/wp-content\/uploads\/2022\/07\/16-18x5.jpg 18w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/>\n<p>\u00a0<\/p>\n<p>\u00a0<\/p>\n<figcaption><em>MBS \u00b7<\/em> Todos los espacios del Montessori British School son obras de arte, que contagian a los estudiantes con su creatividad.<\/figcaption>\n<\/figure>\n<\/div>\n<p><\/p>\n<p><\/p>\n<p class=\"has-drop-cap\">Le preguntamos a Claudia D\u00edaz, directora del Montessori British School, cuales son los 5 aprendizajes m\u00e1s importantes que deben adquirir los ni\u00f1os cuando son peque\u00f1os y esto fue lo que nos contest\u00f3:<\/p>\n<p>\u00a0<\/p>\n<p><strong>Idiomas:\u00a0<\/strong><br \/>\u00abHoy el mundo es muy exigente: las empresas quieren ser globales y necesitan ejecutivos que puedan comunicarse entre continentes y entender las diferencias culturales. Y , adem\u00e1s, aprender otra lengua demanda tiempo y paciencia, algo que muchos adultos no poseen. Por eso en el Montessori British School se estudian y certifican internacionalmente 4 idiomas: ingl\u00e9s, franc\u00e9s, mandar\u00edn y espa\u00f1ol.\u00bb<br \/><br \/><\/p>\n<p><strong>M\u00fasica:<\/strong>\u00a0<br \/>\u00abEst\u00e1 comprobado que al estudiar m\u00fasica los ni\u00f1os desarrollan m\u00e1s las \u00e1reas del cerebro vinculadas al razonamiento y el lenguaje, y que el proceso neuronal es potencializado. Esta es una de las razones, afirma Claudia, de nuestros resultados en las diferentes pruebas internacionales: no solo los resultados m\u00e1s altos en Colombia en las siete pruebas del IGCSE \u2014las m\u00e1s<br \/>conocidas alrededor del mundo\u2014, sino que 5 de 6 estudiantes recibieron el reconocimiento Distinction. En este prestigioso plantel se estudia la m\u00fasica con rigor, y cada ni\u00f1o, sin excepci\u00f3n, llega a integrar un grupo musical.\u00bb<br \/><br \/><\/p>\n<p><strong>Car\u00e1cter:<\/strong><br \/>\u00abSin duda, est\u00e1 demostrado que los rasgos de quienes triunfan los catapultan al \u00e9xito. La mejor noticia es que el car\u00e1cter se puede ense\u00f1ar: como en el Montessori, donde las clases son dise\u00f1adas con este prop\u00f3sito, y los padres participan activamente.\u00bb<br \/><br \/><\/p>\n<p><strong>Salud:<\/strong><br \/>El programa de Ciencias en el Montessori British School busca que el estudiante viva en armon\u00eda con su cuerpo, con los alimentos que ingiere \u2014saludables, alejados de las comidas procesadas\u2014 y con pr\u00e1cticas m\u00e1s naturales y amigables con nuestro medio ambiente. La alimentaci\u00f3n es la base de la salud y se debe ense\u00f1ar desde peque\u00f1os.<\/p>\n<p><strong>Expresi\u00f3n corporal:\u00a0<\/strong><br \/>\u00abNuestro cuerpo es la casa del alma y necesita estar lleno de energ\u00eda para dar origen a nuestras ideas y pensamientos. Los ni\u00f1os del Montessori British School aprenden el amor por su cuerpo y la importancia de ejercitarlo. Est\u00e1 comprobado que las personas comunican m\u00e1s con su cuerpo que con el habla, y por eso el cuerpo es nuestro gran aliado para alcanzar el \u00e9xito.\u00bb<br \/><br \/><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-f0d4e97 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"f0d4e97\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-e89b654\" data-id=\"e89b654\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-1c26402 elementor-cta--skin-classic elementor-animated-content elementor-bg-transform elementor-bg-transform-zoom-in elementor-widget elementor-widget-call-to-action\" data-id=\"1c26402\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"call-to-action.default\">\n\t\t\t\t\t\t\t<div class=\"elementor-cta\">\n\t\t\t\t\t<div class=\"elementor-cta__bg-wrapper\">\n\t\t\t\t<div class=\"elementor-cta__bg elementor-bg\" style=\"background-image: url(https:\/\/mbs.edu.co\/wp-content\/uploads\/2022\/06\/ADMISIONES-PIERROT_075.png);\" role=\"img\" aria-label=\"ADMISIONES-PIERROT_075\"><\/div>\n\t\t\t\t<div class=\"elementor-cta__bg-overlay\"><\/div>\n\t\t\t<\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-cta__content\">\n\t\t\t\t\n\t\t\t\t\t\t\t\t\t<h2 class=\"elementor-cta__title elementor-cta__content-item elementor-content-item\">\n\t\t\t\t\t\tRegresar\t\t\t\t\t<\/h2>\n\t\t\t\t\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-cta__description elementor-cta__content-item elementor-content-item\">\n\t\t\t\t\t\tPrensa, somos un referente a seguir <span style=\"font-family: ABeeZee, var(--nv-fallback-ff)\"><\/span><br>\t\t\t\t\t<\/div>\n\t\t\t\t\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-cta__button-wrapper elementor-cta__content-item elementor-content-item\">\n\t\t\t\t\t<a class=\"elementor-cta__button elementor-button elementor-size-\" href=\"https:\/\/mbs.edu.co\/fr\/montessori-british-school\/\">\n\t\t\t\t\t\tVolver atr\u00e1s\t\t\t\t\t<\/a>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-12737c1\" data-id=\"12737c1\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>","protected":false},"excerpt":{"rendered":"<p>Le preguntamos a Claudia D\u00edaz, directora del Montessori British School, cuales son los 5 aprendizajes m\u00e1s importantes que deben adquirir los ni\u00f1os cuando son peque\u00f1os y esto fue lo que nos contest\u00f3: \u00a0 Idiomas:\u00a0\u00abHoy el mundo es muy exigente: las empresas quieren ser globales y necesitan ejecutivos que puedan comunicarse entre continentes y entender las&hellip;&nbsp;<a href=\"https:\/\/mbs.edu.co\/fr\/5-oportunidades-que-su-hijo-no-debe-perder\/\" rel=\"bookmark\">Lire la suite &raquo;<span class=\"screen-reader-text\">5 Oportunidades que su Hijo no debe perder<\/span><\/a><\/p>","protected":false},"author":6,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"neve_meta_sidebar":"","neve_meta_container":"","neve_meta_enable_content_width":"","neve_meta_content_width":0,"neve_meta_title_alignment":"","neve_meta_author_avatar":"","neve_post_elements_order":"","neve_meta_disable_header":"","neve_meta_disable_footer":"","neve_meta_disable_title":"","footnotes":""},"categories":[2],"tags":[],"class_list":["post-14450","post","type-post","status-publish","format-standard","hentry","category-uncategorized"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>5 Oportunidades que su Hijo no debe perder &#8226; Montessori British School<\/title>\n<meta name=\"description\" content=\"Los 5 aprendizajes que m\u00e1s deben adquirir los ni\u00f1os cuando son peque\u00f1os son idiomas, m\u00fasica, car\u00e1cter, salud y expresi\u00f3n corporal.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/mbs.edu.co\/fr\/5-oportunidades-que-su-hijo-no-debe-perder\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"5 Oportunidades que su Hijo no debe perder &#8226; Montessori British School\" \/>\n<meta property=\"og:description\" content=\"Los 5 aprendizajes que m\u00e1s deben adquirir los ni\u00f1os cuando son peque\u00f1os son idiomas, m\u00fasica, car\u00e1cter, salud y expresi\u00f3n corporal.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/mbs.edu.co\/fr\/5-oportunidades-que-su-hijo-no-debe-perder\/\" \/>\n<meta property=\"og:site_name\" content=\"Montessori British School\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/montessoribritishschool\" \/>\n<meta property=\"article:published_time\" content=\"2022-07-16T16:25:46+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2023-06-02T16:15:06+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/mbs.edu.co\/wp-content\/uploads\/2022\/07\/16.jpg\" \/>\n<meta name=\"author\" content=\"admin\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"admin\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/mbs.edu.co\\\/5-oportunidades-que-su-hijo-no-debe-perder\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/mbs.edu.co\\\/5-oportunidades-que-su-hijo-no-debe-perder\\\/\"},\"author\":{\"name\":\"admin\",\"@id\":\"https:\\\/\\\/mbs.edu.co\\\/#\\\/schema\\\/person\\\/17c898cc62fd38e128e406c4cf778a72\"},\"headline\":\"5 Oportunidades que su Hijo no debe perder\",\"datePublished\":\"2022-07-16T16:25:46+00:00\",\"dateModified\":\"2023-06-02T16:15:06+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/mbs.edu.co\\\/5-oportunidades-que-su-hijo-no-debe-perder\\\/\"},\"wordCount\":416,\"publisher\":{\"@id\":\"https:\\\/\\\/mbs.edu.co\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/mbs.edu.co\\\/5-oportunidades-que-su-hijo-no-debe-perder\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/mbs.edu.co\\\/wp-content\\\/uploads\\\/2022\\\/07\\\/16.jpg\",\"articleSection\":[\"Uncategorized\"],\"inLanguage\":\"fr-FR\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/mbs.edu.co\\\/5-oportunidades-que-su-hijo-no-debe-perder\\\/\",\"url\":\"https:\\\/\\\/mbs.edu.co\\\/5-oportunidades-que-su-hijo-no-debe-perder\\\/\",\"name\":\"5 Oportunidades que su Hijo no debe perder &#8226; Montessori British School\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/mbs.edu.co\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/mbs.edu.co\\\/5-oportunidades-que-su-hijo-no-debe-perder\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/mbs.edu.co\\\/5-oportunidades-que-su-hijo-no-debe-perder\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/mbs.edu.co\\\/wp-content\\\/uploads\\\/2022\\\/07\\\/16.jpg\",\"datePublished\":\"2022-07-16T16:25:46+00:00\",\"dateModified\":\"2023-06-02T16:15:06+00:00\",\"description\":\"Los 5 aprendizajes que m\u00e1s deben adquirir los ni\u00f1os cuando son peque\u00f1os son idiomas, m\u00fasica, car\u00e1cter, salud y expresi\u00f3n corporal.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/mbs.edu.co\\\/5-oportunidades-que-su-hijo-no-debe-perder\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/mbs.edu.co\\\/5-oportunidades-que-su-hijo-no-debe-perder\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/mbs.edu.co\\\/5-oportunidades-que-su-hijo-no-debe-perder\\\/#primaryimage\",\"url\":\"https:\\\/\\\/mbs.edu.co\\\/wp-content\\\/uploads\\\/2022\\\/07\\\/16.jpg\",\"contentUrl\":\"https:\\\/\\\/mbs.edu.co\\\/wp-content\\\/uploads\\\/2022\\\/07\\\/16.jpg\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/mbs.edu.co\\\/5-oportunidades-que-su-hijo-no-debe-perder\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/mbs.edu.co\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"5 Oportunidades que su Hijo no debe perder\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/mbs.edu.co\\\/#website\",\"url\":\"https:\\\/\\\/mbs.edu.co\\\/\",\"name\":\"Montessori British School\",\"description\":\"Colegio mixto calendario B, internacional, multiling\u00fce e intercultural que basa su ense\u00f1anza en la creatividad y la expresi\u00f3n.\",\"publisher\":{\"@id\":\"https:\\\/\\\/mbs.edu.co\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/mbs.edu.co\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/mbs.edu.co\\\/#organization\",\"name\":\"Montessori British School\",\"url\":\"https:\\\/\\\/mbs.edu.co\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/mbs.edu.co\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/mbs.edu.co\\\/wp-content\\\/uploads\\\/2020\\\/10\\\/LOGO-MBS-montessori-2.png\",\"contentUrl\":\"https:\\\/\\\/mbs.edu.co\\\/wp-content\\\/uploads\\\/2020\\\/10\\\/LOGO-MBS-montessori-2.png\",\"width\":800,\"height\":366,\"caption\":\"Montessori British School\"},\"image\":{\"@id\":\"https:\\\/\\\/mbs.edu.co\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/montessoribritishschool\",\"https:\\\/\\\/www.instagram.com\\\/oficialmbs\\\/\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/montessori-british-school-mbs\\\/mycompany\\\/?viewAsMember=true\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/mbs.edu.co\\\/#\\\/schema\\\/person\\\/17c898cc62fd38e128e406c4cf778a72\",\"name\":\"admin\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/59256d3338691b9e98f2122a13934b30a3a6fcb6818583d0374ddf2fb85ea2c2?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/59256d3338691b9e98f2122a13934b30a3a6fcb6818583d0374ddf2fb85ea2c2?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/59256d3338691b9e98f2122a13934b30a3a6fcb6818583d0374ddf2fb85ea2c2?s=96&d=mm&r=g\",\"caption\":\"admin\"},\"sameAs\":[\"https:\\\/\\\/mbs.edu.co\\\/\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"5 Oportunidades que su Hijo no debe perder &#8226; Montessori British School","description":"Los 5 aprendizajes que m\u00e1s deben adquirir los ni\u00f1os cuando son peque\u00f1os son idiomas, m\u00fasica, car\u00e1cter, salud y expresi\u00f3n corporal.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/mbs.edu.co\/fr\/5-oportunidades-que-su-hijo-no-debe-perder\/","og_locale":"fr_FR","og_type":"article","og_title":"5 Oportunidades que su Hijo no debe perder &#8226; Montessori British School","og_description":"Los 5 aprendizajes que m\u00e1s deben adquirir los ni\u00f1os cuando son peque\u00f1os son idiomas, m\u00fasica, car\u00e1cter, salud y expresi\u00f3n corporal.","og_url":"https:\/\/mbs.edu.co\/fr\/5-oportunidades-que-su-hijo-no-debe-perder\/","og_site_name":"Montessori British School","article_publisher":"https:\/\/www.facebook.com\/montessoribritishschool","article_published_time":"2022-07-16T16:25:46+00:00","article_modified_time":"2023-06-02T16:15:06+00:00","og_image":[{"url":"https:\/\/mbs.edu.co\/wp-content\/uploads\/2022\/07\/16.jpg","type":"","width":"","height":""}],"author":"admin","twitter_card":"summary_large_image","twitter_misc":{"\u00c9crit par":"admin","Dur\u00e9e de lecture estim\u00e9e":"2 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/mbs.edu.co\/5-oportunidades-que-su-hijo-no-debe-perder\/#article","isPartOf":{"@id":"https:\/\/mbs.edu.co\/5-oportunidades-que-su-hijo-no-debe-perder\/"},"author":{"name":"admin","@id":"https:\/\/mbs.edu.co\/#\/schema\/person\/17c898cc62fd38e128e406c4cf778a72"},"headline":"5 Oportunidades que su Hijo no debe perder","datePublished":"2022-07-16T16:25:46+00:00","dateModified":"2023-06-02T16:15:06+00:00","mainEntityOfPage":{"@id":"https:\/\/mbs.edu.co\/5-oportunidades-que-su-hijo-no-debe-perder\/"},"wordCount":416,"publisher":{"@id":"https:\/\/mbs.edu.co\/#organization"},"image":{"@id":"https:\/\/mbs.edu.co\/5-oportunidades-que-su-hijo-no-debe-perder\/#primaryimage"},"thumbnailUrl":"https:\/\/mbs.edu.co\/wp-content\/uploads\/2022\/07\/16.jpg","articleSection":["Uncategorized"],"inLanguage":"fr-FR"},{"@type":"WebPage","@id":"https:\/\/mbs.edu.co\/5-oportunidades-que-su-hijo-no-debe-perder\/","url":"https:\/\/mbs.edu.co\/5-oportunidades-que-su-hijo-no-debe-perder\/","name":"5 Oportunidades que su Hijo no debe perder &#8226; Montessori British School","isPartOf":{"@id":"https:\/\/mbs.edu.co\/#website"},"primaryImageOfPage":{"@id":"https:\/\/mbs.edu.co\/5-oportunidades-que-su-hijo-no-debe-perder\/#primaryimage"},"image":{"@id":"https:\/\/mbs.edu.co\/5-oportunidades-que-su-hijo-no-debe-perder\/#primaryimage"},"thumbnailUrl":"https:\/\/mbs.edu.co\/wp-content\/uploads\/2022\/07\/16.jpg","datePublished":"2022-07-16T16:25:46+00:00","dateModified":"2023-06-02T16:15:06+00:00","description":"Los 5 aprendizajes que m\u00e1s deben adquirir los ni\u00f1os cuando son peque\u00f1os son idiomas, m\u00fasica, car\u00e1cter, salud y expresi\u00f3n corporal.","breadcrumb":{"@id":"https:\/\/mbs.edu.co\/5-oportunidades-que-su-hijo-no-debe-perder\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/mbs.edu.co\/5-oportunidades-que-su-hijo-no-debe-perder\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/mbs.edu.co\/5-oportunidades-que-su-hijo-no-debe-perder\/#primaryimage","url":"https:\/\/mbs.edu.co\/wp-content\/uploads\/2022\/07\/16.jpg","contentUrl":"https:\/\/mbs.edu.co\/wp-content\/uploads\/2022\/07\/16.jpg"},{"@type":"BreadcrumbList","@id":"https:\/\/mbs.edu.co\/5-oportunidades-que-su-hijo-no-debe-perder\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/mbs.edu.co\/"},{"@type":"ListItem","position":2,"name":"5 Oportunidades que su Hijo no debe perder"}]},{"@type":"WebSite","@id":"https:\/\/mbs.edu.co\/#website","url":"https:\/\/mbs.edu.co\/","name":"Montessori British School","description":"Colegio mixto calendario B, internacional, multiling\u00fce e intercultural que basa su ense\u00f1anza en la creatividad y la expresi\u00f3n.","publisher":{"@id":"https:\/\/mbs.edu.co\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/mbs.edu.co\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/mbs.edu.co\/#organization","name":"Montessori British School","url":"https:\/\/mbs.edu.co\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/mbs.edu.co\/#\/schema\/logo\/image\/","url":"https:\/\/mbs.edu.co\/wp-content\/uploads\/2020\/10\/LOGO-MBS-montessori-2.png","contentUrl":"https:\/\/mbs.edu.co\/wp-content\/uploads\/2020\/10\/LOGO-MBS-montessori-2.png","width":800,"height":366,"caption":"Montessori British School"},"image":{"@id":"https:\/\/mbs.edu.co\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/montessoribritishschool","https:\/\/www.instagram.com\/oficialmbs\/","https:\/\/www.linkedin.com\/company\/montessori-british-school-mbs\/mycompany\/?viewAsMember=true"]},{"@type":"Person","@id":"https:\/\/mbs.edu.co\/#\/schema\/person\/17c898cc62fd38e128e406c4cf778a72","name":"admin","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/secure.gravatar.com\/avatar\/59256d3338691b9e98f2122a13934b30a3a6fcb6818583d0374ddf2fb85ea2c2?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/59256d3338691b9e98f2122a13934b30a3a6fcb6818583d0374ddf2fb85ea2c2?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/59256d3338691b9e98f2122a13934b30a3a6fcb6818583d0374ddf2fb85ea2c2?s=96&d=mm&r=g","caption":"admin"},"sameAs":["https:\/\/mbs.edu.co\/"]}]}},"_links":{"self":[{"href":"https:\/\/mbs.edu.co\/fr\/wp-json\/wp\/v2\/posts\/14450","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/mbs.edu.co\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/mbs.edu.co\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/mbs.edu.co\/fr\/wp-json\/wp\/v2\/users\/6"}],"replies":[{"embeddable":true,"href":"https:\/\/mbs.edu.co\/fr\/wp-json\/wp\/v2\/comments?post=14450"}],"version-history":[{"count":0,"href":"https:\/\/mbs.edu.co\/fr\/wp-json\/wp\/v2\/posts\/14450\/revisions"}],"wp:attachment":[{"href":"https:\/\/mbs.edu.co\/fr\/wp-json\/wp\/v2\/media?parent=14450"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/mbs.edu.co\/fr\/wp-json\/wp\/v2\/categories?post=14450"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/mbs.edu.co\/fr\/wp-json\/wp\/v2\/tags?post=14450"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}